{"id":3171,"date":"2021-10-07T17:12:34","date_gmt":"2021-10-07T14:12:34","guid":{"rendered":"https:\/\/alanya.law\/de\/?p=3171"},"modified":"2021-10-07T17:12:37","modified_gmt":"2021-10-07T14:12:37","slug":"person-die-obligatorischen-militaerdienst-erfuellt-und-keine-einkommen-oder-vermoegen-verfuegt-kann-nicht-fuer-alimente-verantwortlich-werden","status":"publish","type":"post","link":"https:\/\/alanya.law\/de\/blog\/alanya-rechtsanwalt\/person-die-obligatorischen-militaerdienst-erfuellt-und-keine-einkommen-oder-vermoegen-verfuegt-kann-nicht-fuer-alimente-verantwortlich-werden\/","title":{"rendered":"PERSON, DIE OBLIGATORISCHEN MILIT\u00c4RDIENST ERF\u00dcLLT UND KEINE EINKOMMEN ODER VERM\u00d6GEN VERF\u00dcGT, KANN NICHT F\u00dcR Alimente VERANTWORTLICH WERDEN"},"content":{"rendered":"<!--themify_builder_content-->\n<div id=\"themify_builder_content-3171\" data-postid=\"3171\" class=\"themify_builder_content themify_builder_content-3171 themify_builder tf_clear\">\n    <\/div>\n<!--\/themify_builder_content-->\n\n\n<ol class=\"wp-block-list\" start=\"2\"><li>Rechtsabteilung<\/li><\/ol>\n\n\n\n<p>Hauptnummer: 2016\/20858<\/p>\n\n\n\n<p>Entscheidungsnummer: 2018\/8072<\/p>\n\n\n\n<p>&#8222;Gerechtigkeitstext&#8220;<\/p>\n\n\n\n<p>GERICHT: Zivil-(Familien-)Gericht erster Instanz<br>ART DES FALLS: Gegenseitige Scheidung<\/p>\n\n\n\n<p>Das Urteil des Amtsgerichts am Ende des Verfahrens des Verfahrens zwischen den Parteien, dessen Datum und Nummer oben angegeben sind, wird vom Kl\u00e4ger-Gegenbeklagten-Mann im Hinblick auf den angenommenen Fall der Frau bestimmt , die Verschuldensfeststellung, die abgewiesenen Schadenersatzanspr\u00fcche, Unterhalt und Sorgerecht, sowie die Beklagte-Gegenkl\u00e4gerin, Feststellung, ihre abgewiesenen Schadenersatz-, Armuts- und die H\u00f6he des Beteiligungsunterhalts wurden angefochten, die Unterlagen verlesen und die Notstandsregelung besprochen und \u00fcberlegt:<br>1-Nach den Aktenschrift, den Beweismitteln, auf denen die Entscheidung beruht, den rechtlichen Gr\u00fcnden, insbesondere wenn kein Fehler in der Beweisw\u00fcrdigung erkennbar ist, den Berufungseinw\u00e4nden der Parteien, die nicht in den Anwendungsbereich der Die folgenden Abs\u00e4tze sind unbegr\u00fcndet.<br>2- Obwohl das Gericht beschlossen hat, beide Scheidungsf\u00e4lle zu akzeptieren, indem es die Parteien als gleich mangelhaft in den Ereignissen anerkennt, die zur Scheidung gef\u00fchrt haben; Aus dem Prozess und den gesammelten Beweisen geht hervor, dass der Kl\u00e4ger-gegenangeklagte Mann keine unabh\u00e4ngige Unterkunft zur Verf\u00fcgung stellte, seine Frau bedrohte, seiner Frau k\u00f6rperliche Gewalt zuf\u00fcgte, ihn beleidigte, seine Frau nicht mit seiner Familie treffen lie\u00df, \u00fcber das Eingreifen seiner Familie in Heirat, Drohung und Beleidigung seiner Frau; es wird davon ausgegangen, dass die Beklagte-Gegenkl\u00e4gerin ihren Ehemann beleidigt, ihre Gewerkschaftspflichten vernachl\u00e4ssigt und geschwiegen hat, als ihre Familie in die Ehe eingegriffen, ihren Ehemann bedroht und beleidigt hat. Nach dieser Situation ist anzunehmen, dass der Kl\u00e4ger-Gegenbeklagte in den Ereignissen, die zur Scheidung f\u00fchrten, schwerwiegendere Fehler aufweist als die Beklagte-Gegenkl\u00e4gerin. In dieser Situation war es nicht richtig, die Parteien als gleicherma\u00dfen mangelhaft und r\u00fcckg\u00e4ngig zu machen.<br>3- In F\u00e4llen, die eine Scheidung aus dem im zweiten Absatz oben genannten Grund zur Folge haben, weist der klagende Beklagte einen schwerwiegenden Fehler auf, und dieses fehlerhafte Verhalten stellt auch einen Angriff auf die Pers\u00f6nlichkeitsrechte der Frau dar. Durch die Scheidung wurde der Frau die finanzielle Unterst\u00fctzung ihres Mannes entzogen. Zu Gunsten der Frauen sind die Bedingungen des Artikels 174\/1-2 des t\u00fcrkischen B\u00fcrgerlichen Gesetzbuches erf\u00fcllt. Im Rahmen der sozialen und wirtschaftlichen Verh\u00e4ltnisse der Parteien, der Schwere der M\u00e4ngel und des Grundsatzes der Fairness war die Entscheidung zur schriftlichen Ablehnung nicht richtig und machte eine R\u00fcckabwicklung erforderlich, w\u00e4hrend eine W\u00fcrdigung des finanziellen und moralischen Ausgleichs zugunsten der die Frau war gefragt.<br>4-Es versteht sich, dass der Kl\u00e4ger-Gegen-Angeklagte w\u00e4hrend des Prozesses eingezogen wurde. Ein Mann, der seinen Wehrdienst leistet und kein Einkommen oder Verm\u00f6gen hat, kann nicht f\u00fcr den Unterhalt verantwortlich gemacht werden. W\u00e4hrend der Kl\u00e4ger-Beklagte-Mann w\u00e4hrend seiner Wehrdienstzeit nicht f\u00fcr den vorl\u00e4ufigen Unterhalt verantwortlich gemacht werden sollte, war es nicht richtig, \u00fcber den vorl\u00e4ufigen Unterhalt zugunsten der Beklagten-Gegenkl\u00e4gerin und ihres gemeinsamen Kindes zu entscheiden, einschlie\u00dflich dieser Zeit .<br>5- Je nach den sozialen und wirtschaftlichen Bedingungen der Parteien, der Art des Unterhalts und den wirtschaftlichen Bedingungen des Tages ist der der Beklagten-Gegenkl\u00e4gerin zugesprochene Armutsunterhalt hoch. Ein angemessenerer Unterhaltsbetrag sollte vom Gericht unter Ber\u00fccksichtigung des Billigkeitsgrundsatzes in Artikel 4 des t\u00fcrkischen B\u00fcrgerlichen Gesetzbuchs gew\u00e4hrt werden. Es verst\u00f6\u00dft gegen das Verfahren und das Gesetz, ein schriftliches Urteil zu f\u00e4llen, ohne diesen Aspekt zu beachten.<br>6- Je nach den sozialen und wirtschaftlichen Bedingungen der Parteien, der Art des Unterhalts und den wirtschaftlichen Bedingungen des Tages ist der zum Wohle des gemeinsamen Kindes gesch\u00e4tzte Kindesunterhalt hoch. Unter Ber\u00fccksichtigung des Billigkeitsgrundsatzes in Artikel 4 des t\u00fcrkischen B\u00fcrgerlichen Gesetzbuchs sollte das Gericht \u00fcber einen angemesseneren Unterhalt entscheiden. Es verst\u00f6\u00dft gegen das Verfahren und das Gesetz, ein schriftliches Urteil zu f\u00e4llen, ohne diesen Aspekt zu beachten.<br>SCHLUSSFOLGERUNG: Das angefochtene Urteil wurde aus den oben in den Abs\u00e4tzen 2, 3, 4, 5 und 6 genannten Gr\u00fcnden AUFGEHOBEN, und die anderen Teile der Berufung, die nicht in den Anwendungsbereich der Aufhebung fallen, sind aus den angegebenen Gr\u00fcnden GENEHMIGT im ersten Absatz oben.<br>Es wurde einstimmig beschlossen, die Beschwerdegeb\u00fchr auf Antrag innerhalb von 15 Tagen nach Zustellung dieser Entscheidung an den Einleger zur\u00fcckzuzahlen, wobei die M\u00f6glichkeit der Berichtigung offen ist. 26.06.2018 (Dienstag)<\/p>","protected":false},"excerpt":{"rendered":"<p>Rechtsabteilung Hauptnummer: 2016\/20858 Entscheidungsnummer: 2018\/8072 &#8222;Gerechtigkeitstext&#8220; GERICHT: Zivil-(Familien-)Gericht erster InstanzART DES FALLS: Gegenseitige Scheidung Das Urteil des Amtsgerichts am Ende des Verfahrens des Verfahrens zwischen den Parteien, dessen Datum und Nummer oben angegeben sind, wird vom Kl\u00e4ger-Gegenbeklagten-Mann im Hinblick auf den angenommenen Fall der Frau bestimmt , die Verschuldensfeststellung, die abgewiesenen Schadenersatzanspr\u00fcche, Unterhalt und Sorgerecht, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[16,3113,22,17,6605],"yst_prominent_words":[3104,4209],"class_list":["post-3171","post","type-post","status-publish","format-standard","hentry","category-alanya-rechtsanwalt","tag-alanya","tag-antalya","tag-law","tag-lawyer","tag-scheiden-lassen","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"builder_content":"","_links":{"self":[{"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/posts\/3171"}],"collection":[{"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/comments?post=3171"}],"version-history":[{"count":2,"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/posts\/3171\/revisions"}],"predecessor-version":[{"id":3173,"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/posts\/3171\/revisions\/3173"}],"wp:attachment":[{"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/media?parent=3171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/categories?post=3171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/tags?post=3171"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/alanya.law\/de\/wp-json\/wp\/v2\/yst_prominent_words?post=3171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}